{"id":2116,"date":"2023-04-28T13:52:50","date_gmt":"2023-04-28T11:52:50","guid":{"rendered":"https:\/\/enterozoo.si\/faq\/"},"modified":"2025-10-21T14:33:03","modified_gmt":"2025-10-21T12:33:03","slug":"faq","status":"publish","type":"page","link":"https:\/\/enterozoo.si\/en\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":3513,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-2116","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FAQ | Enterozoo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enterozoo.si\/en\/faq\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FAQ | Enterozoo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enterozoo.si\/en\/faq\/\" \/>\n<meta property=\"og:site_name\" content=\"Enterozoo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnterozooSlovenija\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-21T12:33:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enterozoo.si\/wp-content\/uploads\/2023\/09\/enterozoo_social_logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/enterozoo.si\/en\/faq\/\",\"url\":\"https:\/\/enterozoo.si\/en\/faq\/\",\"name\":\"FAQ | Enterozoo\",\"isPartOf\":{\"@id\":\"https:\/\/enterozoo.si\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/enterozoo.si\/en\/faq\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/enterozoo.si\/en\/faq\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/enterozoo.si\/wp-content\/uploads\/2023\/09\/enterozoo_social_logo.png\",\"datePublished\":\"2023-04-28T11:52:50+00:00\",\"dateModified\":\"2025-10-21T12:33:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/enterozoo.si\/en\/faq\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/enterozoo.si\/en\/faq\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/enterozoo.si\/en\/faq\/#primaryimage\",\"url\":\"https:\/\/enterozoo.si\/wp-content\/uploads\/2023\/09\/enterozoo_social_logo.png\",\"contentUrl\":\"https:\/\/enterozoo.si\/wp-content\/uploads\/2023\/09\/enterozoo_social_logo.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/enterozoo.si\/en\/faq\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/enterozoo.si\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/enterozoo.si\/en\/#website\",\"url\":\"https:\/\/enterozoo.si\/en\/\",\"name\":\"Enterozoo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/enterozoo.si\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/enterozoo.si\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/enterozoo.si\/en\/#organization\",\"name\":\"Enterozoo\",\"alternateName\":\"Enterozoo\",\"url\":\"https:\/\/enterozoo.si\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/enterozoo.si\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/enterozoo.si\/wp-content\/uploads\/2023\/03\/Group.svg\",\"contentUrl\":\"https:\/\/enterozoo.si\/wp-content\/uploads\/2023\/03\/Group.svg\",\"width\":248,\"height\":100,\"caption\":\"Enterozoo\"},\"image\":{\"@id\":\"https:\/\/enterozoo.si\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/EnterozooSlovenija\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FAQ | Enterozoo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enterozoo.si\/en\/faq\/","og_locale":"en_US","og_type":"article","og_title":"FAQ | Enterozoo","og_url":"https:\/\/enterozoo.si\/en\/faq\/","og_site_name":"Enterozoo","article_publisher":"https:\/\/www.facebook.com\/EnterozooSlovenija\/","article_modified_time":"2025-10-21T12:33:03+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/enterozoo.si\/wp-content\/uploads\/2023\/09\/enterozoo_social_logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/enterozoo.si\/en\/faq\/","url":"https:\/\/enterozoo.si\/en\/faq\/","name":"FAQ | Enterozoo","isPartOf":{"@id":"https:\/\/enterozoo.si\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enterozoo.si\/en\/faq\/#primaryimage"},"image":{"@id":"https:\/\/enterozoo.si\/en\/faq\/#primaryimage"},"thumbnailUrl":"https:\/\/enterozoo.si\/wp-content\/uploads\/2023\/09\/enterozoo_social_logo.png","datePublished":"2023-04-28T11:52:50+00:00","dateModified":"2025-10-21T12:33:03+00:00","breadcrumb":{"@id":"https:\/\/enterozoo.si\/en\/faq\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enterozoo.si\/en\/faq\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/enterozoo.si\/en\/faq\/#primaryimage","url":"https:\/\/enterozoo.si\/wp-content\/uploads\/2023\/09\/enterozoo_social_logo.png","contentUrl":"https:\/\/enterozoo.si\/wp-content\/uploads\/2023\/09\/enterozoo_social_logo.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/enterozoo.si\/en\/faq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enterozoo.si\/en\/"},{"@type":"ListItem","position":2,"name":"FAQ"}]},{"@type":"WebSite","@id":"https:\/\/enterozoo.si\/en\/#website","url":"https:\/\/enterozoo.si\/en\/","name":"Enterozoo","description":"","publisher":{"@id":"https:\/\/enterozoo.si\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enterozoo.si\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/enterozoo.si\/en\/#organization","name":"Enterozoo","alternateName":"Enterozoo","url":"https:\/\/enterozoo.si\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/enterozoo.si\/en\/#\/schema\/logo\/image\/","url":"https:\/\/enterozoo.si\/wp-content\/uploads\/2023\/03\/Group.svg","contentUrl":"https:\/\/enterozoo.si\/wp-content\/uploads\/2023\/03\/Group.svg","width":248,"height":100,"caption":"Enterozoo"},"image":{"@id":"https:\/\/enterozoo.si\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnterozooSlovenija\/"]}]}},"_links":{"self":[{"href":"https:\/\/enterozoo.si\/en\/wp-json\/wp\/v2\/pages\/2116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enterozoo.si\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/enterozoo.si\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/enterozoo.si\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/enterozoo.si\/en\/wp-json\/wp\/v2\/comments?post=2116"}],"version-history":[{"count":4,"href":"https:\/\/enterozoo.si\/en\/wp-json\/wp\/v2\/pages\/2116\/revisions"}],"predecessor-version":[{"id":7203,"href":"https:\/\/enterozoo.si\/en\/wp-json\/wp\/v2\/pages\/2116\/revisions\/7203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enterozoo.si\/en\/wp-json\/wp\/v2\/media\/3513"}],"wp:attachment":[{"href":"https:\/\/enterozoo.si\/en\/wp-json\/wp\/v2\/media?parent=2116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}